{"id":1461,"date":"2025-02-07T12:03:14","date_gmt":"2025-02-07T12:03:14","guid":{"rendered":"https:\/\/icelandescape.com\/?p=1461"},"modified":"2025-11-07T15:08:48","modified_gmt":"2025-11-07T15:08:48","slug":"les-bains-de-fontana-a-laugarvatn","status":"publish","type":"post","link":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/","title":{"rendered":"Les bains de Fontana"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":7393,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[13],"tags":[],"class_list":["post-1461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les bains de Fontana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les bains de Fontana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/\" \/>\n<meta property=\"og:site_name\" content=\"Iceland Escape\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-07T12:03:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-07T15:08:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/icelandescape.com\/wp-content\/uploads\/2025\/02\/fontana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"iceland-escape\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"iceland-escape\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/\"},\"author\":{\"name\":\"iceland-escape\",\"@id\":\"https:\\\/\\\/icelandescape.com\\\/#\\\/schema\\\/person\\\/e5e8b149b90ac0be91f815200d6523d9\"},\"headline\":\"Les bains de Fontana\",\"datePublished\":\"2025-02-07T12:03:14+00:00\",\"dateModified\":\"2025-11-07T15:08:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/\"},\"wordCount\":4,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/icelandescape.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/fontana.jpg\",\"articleSection\":[\"Activit\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/\",\"url\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/\",\"name\":\"Les bains de Fontana - Iceland Escape\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/icelandescape.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/icelandescape.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/fontana.jpg\",\"datePublished\":\"2025-02-07T12:03:14+00:00\",\"dateModified\":\"2025-11-07T15:08:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/icelandescape.com\\\/#\\\/schema\\\/person\\\/e5e8b149b90ac0be91f815200d6523d9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/icelandescape.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/fontana.jpg\",\"contentUrl\":\"https:\\\/\\\/icelandescape.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/fontana.jpg\",\"width\":1200,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/les-bains-de-fontana-a-laugarvatn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/icelandescape.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les bains de Fontana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/\",\"name\":\"Iceland Escape\",\"description\":\"Agence francophone bas\u00e9e \u00e0 Reykjav\u00edk\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/icelandescape.com\\\/#\\\/schema\\\/person\\\/e5e8b149b90ac0be91f815200d6523d9\",\"name\":\"iceland-escape\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2a053146bb6eee490571d4936f98c6f37bdf34c7196a526f2ed63b1a6063e47?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2a053146bb6eee490571d4936f98c6f37bdf34c7196a526f2ed63b1a6063e47?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2a053146bb6eee490571d4936f98c6f37bdf34c7196a526f2ed63b1a6063e47?s=96&d=mm&r=g\",\"caption\":\"iceland-escape\"},\"url\":\"https:\\\/\\\/icelandescape.com\\\/en\\\/author\\\/iceland-escape\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les bains de Fontana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/","og_locale":"en_US","og_type":"article","og_title":"Les bains de Fontana","og_url":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/","og_site_name":"Iceland Escape","article_published_time":"2025-02-07T12:03:14+00:00","article_modified_time":"2025-11-07T15:08:48+00:00","og_image":[{"width":1200,"height":1500,"url":"https:\/\/icelandescape.com\/wp-content\/uploads\/2025\/02\/fontana.jpg","type":"image\/jpeg"}],"author":"iceland-escape","twitter_card":"summary_large_image","twitter_misc":{"Written by":"iceland-escape","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/#article","isPartOf":{"@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/"},"author":{"name":"iceland-escape","@id":"https:\/\/icelandescape.com\/#\/schema\/person\/e5e8b149b90ac0be91f815200d6523d9"},"headline":"Les bains de Fontana","datePublished":"2025-02-07T12:03:14+00:00","dateModified":"2025-11-07T15:08:48+00:00","mainEntityOfPage":{"@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/"},"wordCount":4,"commentCount":0,"image":{"@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/#primaryimage"},"thumbnailUrl":"https:\/\/icelandescape.com\/wp-content\/uploads\/2025\/02\/fontana.jpg","articleSection":["Activit\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/","url":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/","name":"Les bains de Fontana - Iceland Escape","isPartOf":{"@id":"https:\/\/icelandescape.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/#primaryimage"},"image":{"@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/#primaryimage"},"thumbnailUrl":"https:\/\/icelandescape.com\/wp-content\/uploads\/2025\/02\/fontana.jpg","datePublished":"2025-02-07T12:03:14+00:00","dateModified":"2025-11-07T15:08:48+00:00","author":{"@id":"https:\/\/icelandescape.com\/#\/schema\/person\/e5e8b149b90ac0be91f815200d6523d9"},"breadcrumb":{"@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/#primaryimage","url":"https:\/\/icelandescape.com\/wp-content\/uploads\/2025\/02\/fontana.jpg","contentUrl":"https:\/\/icelandescape.com\/wp-content\/uploads\/2025\/02\/fontana.jpg","width":1200,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/icelandescape.com\/en\/les-bains-de-fontana-a-laugarvatn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/icelandescape.com\/"},{"@type":"ListItem","position":2,"name":"Les bains de Fontana"}]},{"@type":"WebSite","@id":"https:\/\/icelandescape.com\/en\/#website","url":"https:\/\/icelandescape.com\/en\/","name":"Iceland Escape","description":"Agence francophone bas\u00e9e \u00e0 Reykjav\u00edk","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/icelandescape.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/icelandescape.com\/#\/schema\/person\/e5e8b149b90ac0be91f815200d6523d9","name":"iceland-escape","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b2a053146bb6eee490571d4936f98c6f37bdf34c7196a526f2ed63b1a6063e47?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b2a053146bb6eee490571d4936f98c6f37bdf34c7196a526f2ed63b1a6063e47?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b2a053146bb6eee490571d4936f98c6f37bdf34c7196a526f2ed63b1a6063e47?s=96&d=mm&r=g","caption":"iceland-escape"},"url":"https:\/\/icelandescape.com\/en\/author\/iceland-escape\/"}]}},"_links":{"self":[{"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/posts\/1461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/comments?post=1461"}],"version-history":[{"count":7,"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/posts\/1461\/revisions"}],"predecessor-version":[{"id":7015,"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/posts\/1461\/revisions\/7015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/media\/7393"}],"wp:attachment":[{"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/media?parent=1461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/categories?post=1461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icelandescape.com\/en\/wp-json\/wp\/v2\/tags?post=1461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}